{"id":52,"date":"2016-04-10T07:43:56","date_gmt":"2016-04-10T07:43:56","guid":{"rendered":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/?p=52"},"modified":"2016-04-13T08:11:56","modified_gmt":"2016-04-13T08:11:56","slug":"tendencias-marketing-online","status":"publish","type":"post","link":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/tendencias-marketing-online\/","title":{"rendered":"Tendencias del Marketing On-line"},"content":{"rendered":"<p>Internet ha modificado dr\u00e1sticamente l amanera de comunicarnos. La informaci\u00f3n aparece ahora reflejada en multitud de plataformas y todos y cada uno de nosotros nos hemos convertido de la noche a la ma\u00f1ana en comunicadores, de mayor oi menor inter\u00e9s.<\/p>\n<p>Sin duda, en el terreno del <strong>marketing online<\/strong>, las t\u00e9cnicas de <strong>outbound marketing<\/strong> han ido quedando m\u00e1s yu m\u00e1s atrasada a favor de las nuevas t\u00e1cticas de inbound marketing que, ayudada por las redes sociales y nuevas formas de comunicaci\u00f3n a trav\u00e9s de las diferentes redes que ofrece internet, se ha convertido en la clave que agencias de marketing online, dise\u00f1o web, posicionamiento SEO, <strong>posicionamiento SMO<\/strong> y gestores de contenidos usan para desmarcarse de la competencia.<\/p>\n<p>El contenido original es sin duda el rey de todo posicionamiento de marca y el catalizador de la imagen final de los diferentes usuarios hacia ella.<\/p>\n<p>Con todas estas reglas de juego proponemos las tendencias que creemos que predominar\u00e1n a lo largo de los pr\u00f3ximos dos o tres a\u00f1os en el juego de la captaci\u00f3n y fidelizaci\u00f3n de clientes.<\/p>\n<h2>El contenido tendr\u00e1 mayor importancia que nunca.<\/h2>\n<p>El <a href=\"https:\/\/www.wishingwell.es\/imagen-on-line-redes-sociales\">marketing de contenidos<\/a> ser\u00e1 sin duda, como hemos dicho anteriormente, el rey de este juego. Contenidos originales, \u00fanicos y que sean capaces de reportar un valor a\u00f1adido a los clientes por parte de una marca o producto.<\/p>\n<p>La manera y los medios de publicar ese contenido cobran especial importancia. Desde las redes sociales, pasando por art\u00edculos en el sitio web de la empresa, eNewsletters, case studies, videos y publicaciones en otras webs hasta infograf\u00edas, descargas, manuales y recursos que supongan inter\u00e9s para los usuarios.<\/p>\n<h2>Las redes sociales<\/h2>\n<p>Hasta ahora <strong>Facebook<\/strong>, <strong>Twitter<\/strong> y <strong>Linkedin<\/strong> eran las plataformas sociales preferidas y casi \u00fanicas. Community managers y agencias de marketing online volcaban sus contenidos sobre ellas y difund\u00edan casi cualquier mensaje y contenido.<\/p>\n<p>Ahora parece que ese panorama ha cambiado. Multitud de plataformas sociales aparecen y exigen que las empresas tengan presencia en ellas. Pinterest, Google +, Tumblr, etc,\u2026 Ninguna red puede quedar fuera de la difusi\u00f3n de mensajes empresariales. Adem\u00e1s el contenido debe estar cuidado al m\u00e1ximo y exponer mensajes capaces de atraer a usuarios para poder favorecer conversiones.<\/p>\n<h2>Una imagen vale m\u00e1s que mil palabras<\/h2>\n<p>La imagen cobra protagonismo y lo hace por encima del texto. Una imagen cuidada, una infograf\u00eda bien realizada,\u2026 material de f\u00e1cil asimilaci\u00f3n por parte de los usuarios. Adem\u00e1s la viralizaci\u00f3n de este tipo de contenido est\u00e1 m\u00e1s que demostrada y su r\u00e1pida difusi\u00f3n favorece sobre manera el alcance de cualquier campa\u00f1a de marketing online.<\/p>\n<h2>Contenido adaptado a m\u00f3viles<\/h2>\n<p>EL m\u00f3vil se ha convertido en muy poco espacio de tiempo en el objetivo que empresas y agencias de marketing tratan de alcanzar. Algunas con mayor \u00e9xito y otras con menos.<\/p>\n<p>EL contenido debe estar pensado no s\u00f3lo para una plataforma est\u00e1tica como pueda ser un ordenador personal. Ahora el <strong>m\u00f3vil es un objetivo prioritario<\/strong>, y m\u00e1s si atendemos a la cantidad de informaci\u00f3n que los usuarios consumen a trav\u00e9s de estos dispositivos. Hemos de ser capaces de transmitir informaci\u00f3n a trav\u00e9s de cualquier dispositivo y que esa informaci\u00f3n se lea de la mejor manera posible.<\/p>\n<h2>SEO y SMO<\/h2>\n<p>El SEO, (search engine optimization) tal y como lo conocemos hasta ahora va dando paso, poco a poco a una nueva manera de entender el posicionamiento en buscadores. Ahora hay que posicionarse tambi\u00e9n en redes sociales y para ello nos servimos, cada vez m\u00e1s del SMO (social media optimization).<\/p>\n<p>Los contenidos, una vez m\u00e1s, cobran una especial importancia en este terreno y los profesionales han tenido que adaptarse a las nuevas normas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Internet ha modificado dr\u00e1sticamente l amanera de comunicarnos. La informaci\u00f3n aparece ahora reflejada en multitud de plataformas y todos y cada uno de nosotros nos hemos convertido de la noche a la ma\u00f1ana en comunicadores, de mayor oi menor inter\u00e9s. Sin duda, en el terreno del marketing online, las t\u00e9cnicas de outbound marketing han ido quedando m\u00e1s yu m\u00e1s atrasada a favor de las nuevas t\u00e1cticas de inbound marketing que, ayudada por las redes sociales y nuevas formas de comunicaci\u00f3n a trav\u00e9s de las diferentes redes que ofrece internet, se ha convertido en la clave que agencias de marketing online, dise\u00f1o web, posicionamiento SEO, posicionamiento SMO y gestores de contenidos usan para desmarcarse de la competencia. El contenido original es sin duda el rey de todo posicionamiento de marca y el catalizador de la imagen final de los diferentes usuarios..<\/p>\n","protected":false},"author":1,"featured_media":160,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-online"],"_links":{"self":[{"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/posts\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":3,"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/posts\/52\/revisions"}],"predecessor-version":[{"id":159,"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/posts\/52\/revisions\/159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/media\/160"}],"wp:attachment":[{"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/media?parent=52"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/categories?post=52"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wishingwell.es\/blog-marketing-on-line\/wp-json\/wp\/v2\/tags?post=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}